{"id":58,"count":49,"description":"","link":"https:\/\/anubis-cosmetics.com\/formaciones\/calendario\/category\/corporal\/","name":"Corporal","slug":"corporal","taxonomy":"tribe_events_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/anubis-cosmetics.com\/formaciones\/wp-json\/wp\/v2\/tribe_events_cat\/58"}],"collection":[{"href":"https:\/\/anubis-cosmetics.com\/formaciones\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/anubis-cosmetics.com\/formaciones\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/anubis-cosmetics.com\/formaciones\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}